{"id":1980,"date":"2017-09-20T21:58:40","date_gmt":"2017-09-20T20:58:40","guid":{"rendered":"http:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen.jpg"},"modified":"2017-09-20T21:58:58","modified_gmt":"2017-09-20T20:58:58","slug":"2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen","status":"inherit","type":"attachment","link":"https:\/\/variationsphase.de\/vp\/2017\/09\/zeichnen-lernen-05-licht-und-schatten\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen\/","title":{"rendered":"Zeichnen lernen &#8211; Richtungslinien f\u00fcr den Lichteinfall einzeichnen"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1980","attachment","type-attachment","status-inherit","hentry","","tg-column-two"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"323\" src=\"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-380x323.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-380x323.jpg 380w, https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-768x652.jpg 768w, https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen.jpg 800w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/><\/a><\/p>\n   "},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":679,"file":"2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen.jpg","filesize":76436,"sizes":{"medium":{"file":"2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-380x323.jpg","width":380,"height":323,"filesize":11666,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-380x323.jpg"},"thumbnail":{"file":"2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-150x150.jpg","width":150,"height":150,"filesize":2778,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-150x150.jpg"},"medium_large":{"file":"2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-768x652.jpg","width":768,"height":652,"filesize":47558,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-768x652.jpg"},"featured-blog-large":{"file":"2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-750x350.jpg","width":750,"height":350,"filesize":26643,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-750x350.jpg"},"featured-blog-medium":{"file":"2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-270x270.jpg","width":270,"height":270,"filesize":7640,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-270x270.jpg"},"featured":{"file":"2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-642x300.jpg","width":642,"height":300,"filesize":19891,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-642x300.jpg"},"featured-blog-medium-small":{"file":"2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-230x230.jpg","width":230,"height":230,"filesize":5552,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen-230x230.jpg"},"full":{"file":"2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen.jpg","width":800,"height":679,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":1820,"source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2017\/03\/2017-09_zeichnen-lernen-richtung-von-licht-einzeichnen.jpg","_links":{"self":[{"href":"https:\/\/variationsphase.de\/vp\/wp-json\/wp\/v2\/media\/1980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/variationsphase.de\/vp\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/variationsphase.de\/vp\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/variationsphase.de\/vp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/variationsphase.de\/vp\/wp-json\/wp\/v2\/comments?post=1980"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1820,"href":"https:\/\/variationsphase.de\/vp\/wp-json\/wp\/v2\/posts\/1820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}