{"id":1623,"date":"2016-12-08T22:15:14","date_gmt":"2016-12-08T21:15:14","guid":{"rendered":"http:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken.jpg"},"modified":"2016-12-08T22:15:30","modified_gmt":"2016-12-08T21:15:30","slug":"2016-12-09_weihnachten-gedenken","status":"inherit","type":"attachment","link":"https:\/\/variationsphase.de\/vp\/2016\/12\/9-turchen-gedenken\/2016-12-09_weihnachten-gedenken\/","title":{"rendered":"Eine kleine Weihnachtsgeschichte &#8211; Teil 9"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-1623","attachment","type-attachment","status-inherit","hentry","","tg-column-two"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"380\" height=\"380\" src=\"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken-380x380.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken-380x380.jpg 380w, https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken-150x150.jpg 150w, https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken-270x270.jpg 270w, https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken-230x230.jpg 230w, https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken.jpg 500w\" sizes=\"auto, (max-width: 380px) 100vw, 380px\" \/><\/a><\/p>\n   "},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":500,"height":500,"file":"2016\/12\/2016-12-09_weihnachten-gedenken.jpg","filesize":123458,"sizes":{"medium":{"file":"2016-12-09_weihnachten-gedenken-380x380.jpg","width":380,"height":380,"filesize":34964,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken-380x380.jpg"},"thumbnail":{"file":"2016-12-09_weihnachten-gedenken-150x150.jpg","width":150,"height":150,"filesize":8038,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken-150x150.jpg"},"featured-blog-large":{"file":"2016-12-09_weihnachten-gedenken-500x350.jpg","width":500,"height":350,"filesize":44398,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken-500x350.jpg"},"featured-blog-medium":{"file":"2016-12-09_weihnachten-gedenken-270x270.jpg","width":270,"height":270,"filesize":20291,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken-270x270.jpg"},"featured":{"file":"2016-12-09_weihnachten-gedenken-500x300.jpg","width":500,"height":300,"filesize":39444,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken-500x300.jpg"},"featured-blog-medium-small":{"file":"2016-12-09_weihnachten-gedenken-230x230.jpg","width":230,"height":230,"filesize":15718,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken-230x230.jpg"},"full":{"file":"2016-12-09_weihnachten-gedenken.jpg","width":500,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":1622,"source_url":"https:\/\/variationsphase.de\/vp\/wp-content\/uploads\/2016\/12\/2016-12-09_weihnachten-gedenken.jpg","_links":{"self":[{"href":"https:\/\/variationsphase.de\/vp\/wp-json\/wp\/v2\/media\/1623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/variationsphase.de\/vp\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/variationsphase.de\/vp\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/variationsphase.de\/vp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/variationsphase.de\/vp\/wp-json\/wp\/v2\/comments?post=1623"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":1622,"href":"https:\/\/variationsphase.de\/vp\/wp-json\/wp\/v2\/posts\/1622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}